{"id":1067,"date":"2018-07-17T07:27:36","date_gmt":"2018-07-17T07:27:36","guid":{"rendered":"https:\/\/www.novagear.ch\/175-meter-pro-sekunde\/"},"modified":"2018-07-31T06:08:59","modified_gmt":"2018-07-31T06:08:59","slug":"175-meters-per-second","status":"publish","type":"post","link":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/","title":{"rendered":"175 meters per second &#8230;"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text]&#8230; is the pitch line velocity of a turbo gear unit, which we are currently developing and designing on behalf of a well-known European company. The gearbox shall be operated in e-motor test benches for the automotive sector.<br \/>\nTest benches of this type are intended for functional, performance and durability tests of electric motors used in hybrid and electric vehicles.<\/p>\n<p>Typically, the operating range of such test benches extends to zero speed, with varying loads. By means of an iterative optimization of the rotor dynamic system \u201cbearing &#8211; gear shaft &#8211; coupling\u201d has now been achieved that the gearbox can be operated resonance-free in the entire operating range. This feature is a decisive advantage for the customer.<\/p>\n<p>The gearbox will be manufactured according to our drawings and used in multiple versions at different locations in Europe.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text]&#8230; is the pitch line velocity of a turbo gear unit, which we are currently developing and designing on behalf of a well-known European company. The gearbox shall be operated in e-motor test benches for the automotive sector. Test benches of this type are intended for functional, performance and durability tests of electric motors&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2],"tags":[],"post_series":[],"class_list":["post-1067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>175 meters per second ... - Novagear<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"175 meters per second ... - Novagear\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text]&#8230; is the pitch line velocity of a turbo gear unit, which we are currently developing and designing on behalf of a well-known European company. The gearbox shall be operated in e-motor test benches for the automotive sector. Test benches of this type are intended for functional, performance and durability tests of electric motors&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/\" \/>\n<meta property=\"og:site_name\" content=\"Novagear\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-17T07:27:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-31T06:08:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/07\/novagear_news_175-Meter-pro-sec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admax\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admax\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/\"},\"author\":{\"name\":\"admax\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#\\\/schema\\\/person\\\/9dbc66a9f762383b7279c27138900361\"},\"headline\":\"175 meters per second &#8230;\",\"datePublished\":\"2018-07-17T07:27:36+00:00\",\"dateModified\":\"2018-07-31T06:08:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/\"},\"wordCount\":158,\"publisher\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.novagear.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/novagear_news_175-Meter-pro-sec.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/\",\"url\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/\",\"name\":\"175 meters per second ... - Novagear\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.novagear.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/novagear_news_175-Meter-pro-sec.jpg\",\"datePublished\":\"2018-07-17T07:27:36+00:00\",\"dateModified\":\"2018-07-31T06:08:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.novagear.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/novagear_news_175-Meter-pro-sec.jpg\",\"contentUrl\":\"https:\\\/\\\/www.novagear.ch\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/novagear_news_175-Meter-pro-sec.jpg\",\"width\":500,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/175-meters-per-second\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"175 meters per second &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.novagear.ch\\\/\",\"name\":\"Novagear\",\"description\":\"der Spezialist f\u00fcr Zahnradgetriebe\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.novagear.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#organization\",\"name\":\"Novagear\",\"url\":\"https:\\\/\\\/www.novagear.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.novagear.ch\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/novalink_logo_svg.svg\",\"contentUrl\":\"https:\\\/\\\/www.novagear.ch\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/novalink_logo_svg.svg\",\"caption\":\"Novagear\"},\"image\":{\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.novagear.ch\\\/#\\\/schema\\\/person\\\/9dbc66a9f762383b7279c27138900361\",\"name\":\"admax\",\"url\":\"https:\\\/\\\/www.novagear.ch\\\/en\\\/author\\\/admax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"175 meters per second ... - Novagear","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/","og_locale":"en_US","og_type":"article","og_title":"175 meters per second ... - Novagear","og_description":"[vc_row][vc_column width=&#8221;2\/3&#8243;][vc_column_text]&#8230; is the pitch line velocity of a turbo gear unit, which we are currently developing and designing on behalf of a well-known European company. The gearbox shall be operated in e-motor test benches for the automotive sector. Test benches of this type are intended for functional, performance and durability tests of electric motors&hellip;","og_url":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/","og_site_name":"Novagear","article_published_time":"2018-07-17T07:27:36+00:00","article_modified_time":"2018-07-31T06:08:59+00:00","og_image":[{"width":500,"height":330,"url":"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/07\/novagear_news_175-Meter-pro-sec.jpg","type":"image\/jpeg"}],"author":"admax","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admax","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/#article","isPartOf":{"@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/"},"author":{"name":"admax","@id":"https:\/\/www.novagear.ch\/#\/schema\/person\/9dbc66a9f762383b7279c27138900361"},"headline":"175 meters per second &#8230;","datePublished":"2018-07-17T07:27:36+00:00","dateModified":"2018-07-31T06:08:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/"},"wordCount":158,"publisher":{"@id":"https:\/\/www.novagear.ch\/#organization"},"image":{"@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/#primaryimage"},"thumbnailUrl":"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/07\/novagear_news_175-Meter-pro-sec.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/","url":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/","name":"175 meters per second ... - Novagear","isPartOf":{"@id":"https:\/\/www.novagear.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/#primaryimage"},"image":{"@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/#primaryimage"},"thumbnailUrl":"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/07\/novagear_news_175-Meter-pro-sec.jpg","datePublished":"2018-07-17T07:27:36+00:00","dateModified":"2018-07-31T06:08:59+00:00","breadcrumb":{"@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.novagear.ch\/en\/175-meters-per-second\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/#primaryimage","url":"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/07\/novagear_news_175-Meter-pro-sec.jpg","contentUrl":"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/07\/novagear_news_175-Meter-pro-sec.jpg","width":500,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/www.novagear.ch\/en\/175-meters-per-second\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.novagear.ch\/en\/"},{"@type":"ListItem","position":2,"name":"175 meters per second &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.novagear.ch\/#website","url":"https:\/\/www.novagear.ch\/","name":"Novagear","description":"der Spezialist f\u00fcr Zahnradgetriebe","publisher":{"@id":"https:\/\/www.novagear.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.novagear.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.novagear.ch\/#organization","name":"Novagear","url":"https:\/\/www.novagear.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.novagear.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/04\/novalink_logo_svg.svg","contentUrl":"https:\/\/www.novagear.ch\/wp-content\/uploads\/2018\/04\/novalink_logo_svg.svg","caption":"Novagear"},"image":{"@id":"https:\/\/www.novagear.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.novagear.ch\/#\/schema\/person\/9dbc66a9f762383b7279c27138900361","name":"admax","url":"https:\/\/www.novagear.ch\/en\/author\/admax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/posts\/1067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/comments?post=1067"}],"version-history":[{"count":2,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/posts\/1067\/revisions"}],"predecessor-version":[{"id":1069,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/posts\/1067\/revisions\/1069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/media\/1047"}],"wp:attachment":[{"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/media?parent=1067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/categories?post=1067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/tags?post=1067"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/www.novagear.ch\/en\/wp-json\/wp\/v2\/post_series?post=1067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}